{"id":7828,"date":"2020-10-26T14:43:00","date_gmt":"2020-10-26T14:43:00","guid":{"rendered":"https:\/\/mazzoleniart.com\/?post_type=elenco_fiere&#038;p=7828"},"modified":"2021-06-09T17:53:13","modified_gmt":"2021-06-09T17:53:13","slug":"tefaf-online-2020","status":"publish","type":"elenco_fiere","link":"https:\/\/mazzoleniart.com\/it\/elenco_fiere\/tefaf-online-2020\/","title":{"rendered":"TEFAF ONLINE NEW YORK 2020"},"content":{"rendered":"<p>Mazzoleni \u00e8 lieta di annunciare la sua partecipazione a <strong>TEFAF ONLINE NEW YORK 2020<\/strong>.<br \/>\nSu invito di TEFAF a presentare una delle opere d&#8217;arte pi\u00f9 rappresentative della nostra galleria, abbiamo selezionato un&#8217;opera iconica di <strong>Giacomo Balla<\/strong>, parte dei paesaggi\u00a0<em>Linee Forze di Mare <\/em>e realizzata nel 1919 durante un viaggio a Viareggio e parte della sua serie di paesaggi.<br \/>\nIl nucleo di opere intitolate <em>Linee Forze di Mare<\/em> incarna alla perfezione la ricerca rivoluzionaria cromatica e formale di Balla nonch\u00e9 gli ideali futuristi di velocit\u00e0 e movimento, che ambivano a rappresentare lo spirito dell&#8217;et\u00e0 moderna.<\/p>\n<p>E\u2019 possibile accedere alla viewing room di <strong>TEFAF ONLINE NEW YORK 2020<\/strong>\u00a0cliccando su questo <strong><a href=\"https:\/\/www.tefaf.com\/visitors\/sign_up\">LINK<\/a><\/strong><\/p>\n","protected":false},"template":"","class_list":["post-7828","elenco_fiere","type-elenco_fiere","status-publish","hentry"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/mazzoleniart.com\/it\/wp-json\/wp\/v2\/elenco_fiere\/7828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mazzoleniart.com\/it\/wp-json\/wp\/v2\/elenco_fiere"}],"about":[{"href":"https:\/\/mazzoleniart.com\/it\/wp-json\/wp\/v2\/types\/elenco_fiere"}],"version-history":[{"count":1,"href":"https:\/\/mazzoleniart.com\/it\/wp-json\/wp\/v2\/elenco_fiere\/7828\/revisions"}],"predecessor-version":[{"id":7871,"href":"https:\/\/mazzoleniart.com\/it\/wp-json\/wp\/v2\/elenco_fiere\/7828\/revisions\/7871"}],"wp:attachment":[{"href":"https:\/\/mazzoleniart.com\/it\/wp-json\/wp\/v2\/media?parent=7828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}